{"id":15178,"date":"2021-06-25T08:26:21","date_gmt":"2021-06-25T06:26:21","guid":{"rendered":"https:\/\/it-service.network\/blog\/?p=15178"},"modified":"2021-06-25T08:26:21","modified_gmt":"2021-06-25T06:26:21","slug":"cloud-kosten","status":"publish","type":"post","link":"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/","title":{"rendered":"Cloud-Kosten ## Kleine Unternehmen zahlen oft zu viel f\u00fcr die Cloud"},"content":{"rendered":"<p><strong>Die Cloud-Kosten f\u00fcr Unternehmen liegen bis zu 70 Prozent \u00fcber dem, was eigentlich notwendig w\u00e4re. Zu diesem \u2013 relativ erschreckenden \u2013 Ergebnis kommt das Marktforschungsinstitut Gartner. Aber warum ist das so, wo die Cloud doch allgemein als Kostensenker bekannt ist?<\/strong><br \/>\nDie Antwort ist einfach, die L\u00f6sung f\u00fcr dieses Kostenproblem ebenso. Erfahren Sie nachfolgend mehr.<br \/>\n<!--more--><\/p>\n<div style=\"background: #f2f2f2; padding: 15px 15px 5px; margin: 30px 0;\">\n<strong>Dieser Beitrag im \u00dcberblick:<\/strong><\/p>\n<ol style=\"line-height: 1.7;\">\n<li><a href=\"#eins\">Cloud-Kosten h\u00e4ufig zu hoch<\/a><\/li>\n<li><a href=\"#zwei\">H\u00e4ufige Ursachen f\u00fcr zu hohe Cloud-Kosten<\/a><\/li>\n<li><a href=\"#drei\">Kostenoptimierung f\u00fcr die Cloud \u2013 Tipps mit Sofort-Effekt<\/a><\/li>\n<li><a href=\"#vier\">Cloud-Management \u2013 die L\u00f6sung f\u00fcr Ihre Probleme<\/a><\/li>\n<\/ol>\n<\/div>\n<div id=\"attachment_16785\" style=\"width: 310px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-16785\" class=\"size-medium wp-image-16785\" src=\"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2020\/11\/Cloud-Kosten-1-300x222.jpg\" alt=\"Zu sehen ist eine Wolke aus Cent-M\u00fcnzen. Es geht um Cloud-Kosten. Bild: Unsplash\/Marcel Strau\u00df\/Montage IT-SERVICE.NETWORK\" width=\"300\" height=\"222\" srcset=\"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2020\/11\/Cloud-Kosten-1-300x222.jpg 300w, https:\/\/it-service.network\/blog\/wp-content\/uploads\/2020\/11\/Cloud-Kosten-1.jpg 650w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-16785\" class=\"wp-caption-text\">Cloud-Kosten: Unternehmen ohne Cloud-Management zahlen h\u00e4ufig mehr als n\u00f6tig. Bild: Unsplash\/Marcel Strau\u00df\/Montage IT-SERVICE.NETWORK<\/p><\/div>\n<h3 id=\"eins\">Cloud-Kosten h\u00e4ufig zu hoch<\/h3>\n<p>Wer zur Cloud wechselt, spart nicht zwingend Geld. Das klingt erst einmal paradox, denn schlie\u00dflich ist normalerweise eines der Kernargumente f\u00fcr den Umstieg in die Cloud, dass die Kosten skalierbar sind und dadurch sinken. In der Praxis ist das allerdings nur der Fall, wenn das Thema <strong>Kostenoptimierung<\/strong> im Blick behalten wird. Und genau daran scheitert das Projekt bei vielen kleinen und mittelst\u00e4ndischen Unternehmen.<br \/>\nAnders ausgedr\u00fcckt: Wer die Cloud nutzt, aber niemanden besch\u00e4ftigt, der Faktoren wie die Nutzeranzahl und den Speicherplatz im Blick beh\u00e4lt, kann am Ende ordentlich draufzahlen. Umgekehrt lassen sich hohe Kosten einsparen, man muss eben nur wissen, worauf bei einer kosteneffektiven Cloud-Nutzung genau zu achten ist.<\/p>\n<h3 id=\"zwei\">H\u00e4ufige Ursachen f\u00fcr zu hohe Cloud-Kosten<\/h3>\n<p>Die Cloud bietet ein enormes Einsparpotential, dieses muss aber auch genutzt werden. Dass das h\u00e4ufig nicht der Fall ist, zeigt jetzt eine Erhebung von Gartner. Die Gr\u00fcnde f\u00fcr die teilweise sogar explodierenden Kosten lassen sich \u00fcbergeordnet mit einem <strong>fehlenden Cloud-Management<\/strong> zusammenfassen. Wirft man hingegen einen Blick auf die Details, zeigt sich, dass die Ursachen enorm vielf\u00e4ltig sein k\u00f6nnen. Das Problem beginnt allerdings meist schon damit, dass viele Unternehmen nicht genau wissen, an welchen Stellen \u00fcberhaupt Kosten entstehen.<br \/>\nH\u00e4ufig fehlt es auch an <strong>Verst\u00e4ndnis<\/strong> und <strong>Transparenz<\/strong> bez\u00fcglich der <strong>Abrechnungsmodelle<\/strong> der Anbieter. Beispiel AWS, immerhin einer der gr\u00f6\u00dften Cloud-Anbieter \u00fcberhaupt: Die Kostenfaktoren lassen sich grob den \u00fcbergeordneten Bereichen Anfragen, Zeit, Transfer, Speicher und erweiterter Services zuteilen. Insgesamt erstreckt sich die Dimension des Angebots aber auf mehr als 175 Services. Jeder davon hat in der Regel ein bis zwei Kostendimensionen. Kein Wunder also, dass es f\u00fcr den Laien sehr schnell sehr un\u00fcbersichtlich wird.<\/p>\n<h3 id=\"drei\">Kostenoptimierung f\u00fcr die Cloud \u2013 Tipps mit Sofort-Effekt<\/h3>\n<p>Manchmal ist es einfach nur die Summe kleiner Teile \u2013 das gilt auch f\u00fcr die Cloud-Kosten. Mit ein paar einfachen Tricks lassen sich viele Kosten einsparen, auch wenn um die Implementierung eines generellen Cloud-Managements kein Unternehmen herumkommt. Nun aber zu unseren Tipps:<\/p>\n<ul>\n<li><strong>Migrationsstrategie festlegen:<\/strong><br \/>\nDer ultimative Tipp f\u00fcr alle, die den Wechsel anstreben, aber noch nicht vollzogen haben. Auf Basis des <strong>\u201e7-Rs-Prinzips\u201c<\/strong> werden Workloads und Applikationen mit einer passgenauen Strategie migriert, wodurch sich das volle Cloud-Potential bei minimaler Kostenentstehung aussch\u00f6pfen l\u00e4sst.<\/li>\n<li><strong>Optimierung der Instanzgr\u00f6\u00dfen und -typen:<br \/>\n<\/strong>Warum etwas bezahlen, was man nicht nutzt? Achten Sie darauf, dass die festgelegten Instanzgr\u00f6\u00dfen und -typen wirklich zu Ihren Anforderungen passen. Falls nicht, optimieren Sie sie.<\/li>\n<li><strong>Stromtarif wechseln &amp; Strompreis optimieren:<br \/>\n<\/strong>Was im Privathaushalt Sinn macht, kann auch Unternehmen bares Geld sparen. Checken Sie mindestens einmal j\u00e4hrlich die Entwicklungen Ihres Stromtarifs und pr\u00fcfen Sie Wechselm\u00f6glichkeiten. In reduzierter Form funktioniert das auch auf Cloud-Anbieter-Ebene. Es gibt Modelle, bei denen die Kosten pro GByte-Monat niedriger ausfallen, ebenso welche mit verringerter Redundanz. Gibt es Daten, auf die sehr selten zugegriffen werden muss, bietet sich ein Wechsel in eine Klasse an, bei der der Datenabruf zwar l\u00e4nger dauert, aber daf\u00fcr auch g\u00fcnstiger ist.<\/li>\n<li><strong>Test- und Entwicklungsumgebungen checken:<br \/>\n<\/strong>Pr\u00fcfen Sie, ob s\u00e4mtliche Umgebungen wirklich 24\/7 am Laufen gehalten werden m\u00fcssen. Gleiches gilt f\u00fcr <strong>Datenbanken<\/strong>, Elastic-IPs und Load Balancer. Alles, was nicht permanent genutzt werden muss, sollte abgeschaltet werden. Allein dadurch lassen sich Statistiken zufolge 76 Prozent der Kosten f\u00fcr diese Umgebungen einsparen.<\/li>\n<\/ul>\n<p>Unsere Empfehlung: Pr\u00fcfen Sie doch einmal nach, ob Sie diese Tipps bereits umsetzen; falls nicht sollten Sie sich \u00fcberlegen, ob die Tipps auch in Ihrem Unternehmen zu einer kosteneffizienteren Cloud-Nutzung verhelfen k\u00f6nnten.<\/p>\n<h3 id=\"vier\">Cloud-Management \u2013 die L\u00f6sung f\u00fcr Ihre Probleme<\/h3>\n<p>Wer langfristig nicht nur Kosten sparen, sondern auch seine Effizienz steigern m\u00f6chte, sollte ein Cloud-Management etablieren. Am einfachsten gelingt das mit der Unterst\u00fctzung durch einen professionellen IT-Dienstleister \u2013 zum Beispiel unseren <a href=\"https:\/\/it-service.network\/it-dienstleister-finden?q=\" target=\"_blank\" rel=\"noopener noreferrer\">Fachleuten aus dem IT-SERVICE.NETWORK<\/a>.<br \/>\nDas geschulte IT-Personal in unserem Netzwerk bietet Ihnen <a href=\"https:\/\/it-service.network\/it-dienstleistungen\">zahlreiche IT-Dienstleistungen<\/a> und unterst\u00fctzt Sie nat\u00fcrlich auch bei allen Aufgaben rund um <a href=\"https:\/\/it-service.network\/cloud-computing\">Cloud-L\u00f6sungen<\/a> \u2013 von der Migration in die Cloud bis zum laufenden Management. Dazu stimmen unsere Fachleute den Bedarf genau mit Ihnen ab und pr\u00fcfen sp\u00e4ter immer wieder nach, ob Sie diesen Bedarf auch tats\u00e4chlich brauchen oder ob sich durch eine Anpassung sogar Cloud-Kosten einsparen lie\u00dfen. Nehmen Sie unverbindlich Kontakt zu uns auf und lassen Sie sich individuell beraten.<\/p>\n<hr \/>\n<p><small><strong> Weiterf\u00fchrende Links:<\/strong><br \/>\n<a href=\"https:\/\/www.it-daily.net\/it-management\/cloud-computing\/26168-ausufernden-cloud-kosten-mit-kostenoptimierung-entgegentreten\" target=\"_blank\" rel=\"noopener\">it-daily<\/a>, <a href=\"https:\/\/www.gartner.com\/en\" target=\"_blank\" rel=\"noopener\">Gartner<\/a>, <a href=\"https:\/\/aws.amazon.com\/de\/what-is-aws\/\">AWS<\/a>, <a href=\"https:\/\/www.citrix.com\/blogs\/2019\/05\/14\/the-7-rs-of-the-application-landscape\/\" target=\"_blank\" rel=\"noopener\">citrix<\/a><\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Cloud-Kosten f\u00fcr Unternehmen liegen bis zu 70 Prozent \u00fcber dem, was eigentlich notwendig w\u00e4re. Zu diesem \u2013 relativ erschreckenden \u2013 Ergebnis kommt das Marktforschungsinstitut Gartner. Aber warum ist das so, wo die Cloud doch allgemein als Kostensenker bekannt ist? Die Antwort ist einfach, die L\u00f6sung f\u00fcr dieses Kostenproblem ebenso. Erfahren Sie nachfolgend mehr.<\/p>\n","protected":false},"author":14,"featured_media":16785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[131,14],"class_list":["post-15178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cloud-loesungen","tag-cloud-management","tag-cloud-services"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cloud-Kosten \u2013 kleine Unternehmen zahlen oft zu viel<\/title>\n<meta name=\"description\" content=\"Die Cloud-Kosten sind bei vielen kleinen Unternehmen deutlich h\u00f6her als eigentlich notwendig. Wir erkl\u00e4ren, was Sie dagegen tun k\u00f6nnen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cloud-Kosten \u2013 kleine Unternehmen zahlen oft zu viel\" \/>\n<meta property=\"og:description\" content=\"Die Cloud-Kosten sind bei vielen kleinen Unternehmen deutlich h\u00f6her als eigentlich notwendig. Wir erkl\u00e4ren, was Sie dagegen tun k\u00f6nnen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/\" \/>\n<meta property=\"og:site_name\" content=\"IT-SERVICE.NETWORK Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/itservicenetwork\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-25T06:26:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2020\/11\/Cloud-Kosten-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"481\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lena Klaus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ITSERVICNETWORK\" \/>\n<meta name=\"twitter:site\" content=\"@ITSERVICNETWORK\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lena Klaus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/\",\"url\":\"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/\",\"name\":\"Cloud-Kosten \u2013 kleine Unternehmen zahlen oft zu viel\",\"isPartOf\":{\"@id\":\"https:\/\/it-service.network\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2020\/11\/Cloud-Kosten-1.jpg\",\"datePublished\":\"2021-06-25T06:26:21+00:00\",\"author\":{\"@id\":\"https:\/\/it-service.network\/blog\/#\/schema\/person\/9cffbe4f537d5e70bde59b560ce9aac6\"},\"description\":\"Die Cloud-Kosten sind bei vielen kleinen Unternehmen deutlich h\u00f6her als eigentlich notwendig. Wir erkl\u00e4ren, was Sie dagegen tun k\u00f6nnen.\",\"breadcrumb\":{\"@id\":\"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/#primaryimage\",\"url\":\"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2020\/11\/Cloud-Kosten-1.jpg\",\"contentUrl\":\"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2020\/11\/Cloud-Kosten-1.jpg\",\"width\":650,\"height\":481,\"caption\":\"Cloud-Kosten: Unternehmen ohne Cloud-Management zahlen h\u00e4ufig mehr als n\u00f6tig. Bild: Unsplash\/Marcel Strau\u00df\/Montage IT-SERVICE.NETWORK\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/it-service.network\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cloud-Kosten ## Kleine Unternehmen zahlen oft zu viel f\u00fcr die Cloud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/it-service.network\/blog\/#website\",\"url\":\"https:\/\/it-service.network\/blog\/\",\"name\":\"IT-SERVICE.NETWORK Blog\",\"description\":\"Der IT-SERVICE.NETWORK Blog mit spannenden IT-News: \u2713 IT-Themen \u2713 IT-Trends \u2713 Business-Themen \u2713 IT-Dienstleistungen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/it-service.network\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/it-service.network\/blog\/#\/schema\/person\/9cffbe4f537d5e70bde59b560ce9aac6\",\"name\":\"Lena Klaus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/it-service.network\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2019\/04\/lena-klaus-96x96.jpg\",\"contentUrl\":\"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2019\/04\/lena-klaus-96x96.jpg\",\"caption\":\"Lena Klaus\"},\"description\":\"Lena Klaus arbeitet seit 2018 als freie Autorin und SEO-Expertin f\u00fcr das IT-SERVICE.NETWORK. Besonders die Themen rund um den digitalen Wandel und New Work haben es ihr angetan. Dar\u00fcber hinaus ist die erfahrene Texterin immer wieder fasziniert davon, welche neue Methoden und Tricks Hackern und Cyberkriminellen einfallen. Seit 2013 kennt Lena Klaus die IT-Branche und hat sich in diesem Zusammenhang auf die Erstellung von Webtexten und Blogartikeln f\u00fcr B2C- und B2B-orientierte Content-Plattformen spezialisiert. Bis zu ihrer Elternzeit im Jahr 2017 war sie als Content Marketing- und PR-Managerin bei der SYNAXON AG, dem Mutterunternehmen des IT-SERVICE.NETWORK, fest angestellt. W\u00e4hrend dieser T\u00e4tigkeit verantwortete sie nicht nur die allgemeine Unternehmenskommunikation und Pressearbeit, sondern auch s\u00e4mtlichen Content der SYNAXON-Marke PC-SPEZIALIST. Nach ihrer Elternzeit wechselte sie hauptberuflich die Branche, blieb der SYNAXON AG und der mittlerweile fest etablierten Marke IT-SERVICE.NETWORK aber weiterhin als freie Mitarbeiterin treu. Neben ihrer Arbeit als Redakteurin f\u00fcr den IT-SERVICE.NETWORK-Blog verfasst sie auch Texte f\u00fcr das IT-SERVICE.NETWORK-Lexikon, einzelne Themenseiten, Leistungsbeschreibungen oder Profilseiten der Partner. In ihrer Freizeit bleibt der Laptop dann allerdings meist aus: Sie genie\u00dft die Zeit mit Ihrem Mann (nat\u00fcrlich auch ein ITler) und ihrer Tochter \u2013 am liebsten auf Reisen in fernen L\u00e4ndern.\",\"sameAs\":[\"https:\/\/it-service.network\/\"],\"url\":\"https:\/\/it-service.network\/blog\/author\/lena-klaus\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cloud-Kosten \u2013 kleine Unternehmen zahlen oft zu viel","description":"Die Cloud-Kosten sind bei vielen kleinen Unternehmen deutlich h\u00f6her als eigentlich notwendig. Wir erkl\u00e4ren, was Sie dagegen tun k\u00f6nnen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/","og_locale":"de_DE","og_type":"article","og_title":"Cloud-Kosten \u2013 kleine Unternehmen zahlen oft zu viel","og_description":"Die Cloud-Kosten sind bei vielen kleinen Unternehmen deutlich h\u00f6her als eigentlich notwendig. Wir erkl\u00e4ren, was Sie dagegen tun k\u00f6nnen.","og_url":"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/","og_site_name":"IT-SERVICE.NETWORK Blog","article_publisher":"https:\/\/www.facebook.com\/itservicenetwork\/","article_published_time":"2021-06-25T06:26:21+00:00","og_image":[{"width":650,"height":481,"url":"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2020\/11\/Cloud-Kosten-1.jpg","type":"image\/jpeg"}],"author":"Lena Klaus","twitter_card":"summary_large_image","twitter_creator":"@ITSERVICNETWORK","twitter_site":"@ITSERVICNETWORK","twitter_misc":{"Verfasst von":"Lena Klaus","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/","url":"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/","name":"Cloud-Kosten \u2013 kleine Unternehmen zahlen oft zu viel","isPartOf":{"@id":"https:\/\/it-service.network\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/#primaryimage"},"image":{"@id":"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/#primaryimage"},"thumbnailUrl":"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2020\/11\/Cloud-Kosten-1.jpg","datePublished":"2021-06-25T06:26:21+00:00","author":{"@id":"https:\/\/it-service.network\/blog\/#\/schema\/person\/9cffbe4f537d5e70bde59b560ce9aac6"},"description":"Die Cloud-Kosten sind bei vielen kleinen Unternehmen deutlich h\u00f6her als eigentlich notwendig. Wir erkl\u00e4ren, was Sie dagegen tun k\u00f6nnen.","breadcrumb":{"@id":"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/#primaryimage","url":"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2020\/11\/Cloud-Kosten-1.jpg","contentUrl":"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2020\/11\/Cloud-Kosten-1.jpg","width":650,"height":481,"caption":"Cloud-Kosten: Unternehmen ohne Cloud-Management zahlen h\u00e4ufig mehr als n\u00f6tig. Bild: Unsplash\/Marcel Strau\u00df\/Montage IT-SERVICE.NETWORK"},{"@type":"BreadcrumbList","@id":"https:\/\/it-service.network\/blog\/2021\/06\/25\/cloud-kosten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/it-service.network\/blog\/"},{"@type":"ListItem","position":2,"name":"Cloud-Kosten ## Kleine Unternehmen zahlen oft zu viel f\u00fcr die Cloud"}]},{"@type":"WebSite","@id":"https:\/\/it-service.network\/blog\/#website","url":"https:\/\/it-service.network\/blog\/","name":"IT-SERVICE.NETWORK Blog","description":"Der IT-SERVICE.NETWORK Blog mit spannenden IT-News: \u2713 IT-Themen \u2713 IT-Trends \u2713 Business-Themen \u2713 IT-Dienstleistungen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/it-service.network\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/it-service.network\/blog\/#\/schema\/person\/9cffbe4f537d5e70bde59b560ce9aac6","name":"Lena Klaus","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/it-service.network\/blog\/#\/schema\/person\/image\/","url":"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2019\/04\/lena-klaus-96x96.jpg","contentUrl":"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2019\/04\/lena-klaus-96x96.jpg","caption":"Lena Klaus"},"description":"Lena Klaus arbeitet seit 2018 als freie Autorin und SEO-Expertin f\u00fcr das IT-SERVICE.NETWORK. Besonders die Themen rund um den digitalen Wandel und New Work haben es ihr angetan. Dar\u00fcber hinaus ist die erfahrene Texterin immer wieder fasziniert davon, welche neue Methoden und Tricks Hackern und Cyberkriminellen einfallen. Seit 2013 kennt Lena Klaus die IT-Branche und hat sich in diesem Zusammenhang auf die Erstellung von Webtexten und Blogartikeln f\u00fcr B2C- und B2B-orientierte Content-Plattformen spezialisiert. Bis zu ihrer Elternzeit im Jahr 2017 war sie als Content Marketing- und PR-Managerin bei der SYNAXON AG, dem Mutterunternehmen des IT-SERVICE.NETWORK, fest angestellt. W\u00e4hrend dieser T\u00e4tigkeit verantwortete sie nicht nur die allgemeine Unternehmenskommunikation und Pressearbeit, sondern auch s\u00e4mtlichen Content der SYNAXON-Marke PC-SPEZIALIST. Nach ihrer Elternzeit wechselte sie hauptberuflich die Branche, blieb der SYNAXON AG und der mittlerweile fest etablierten Marke IT-SERVICE.NETWORK aber weiterhin als freie Mitarbeiterin treu. Neben ihrer Arbeit als Redakteurin f\u00fcr den IT-SERVICE.NETWORK-Blog verfasst sie auch Texte f\u00fcr das IT-SERVICE.NETWORK-Lexikon, einzelne Themenseiten, Leistungsbeschreibungen oder Profilseiten der Partner. In ihrer Freizeit bleibt der Laptop dann allerdings meist aus: Sie genie\u00dft die Zeit mit Ihrem Mann (nat\u00fcrlich auch ein ITler) und ihrer Tochter \u2013 am liebsten auf Reisen in fernen L\u00e4ndern.","sameAs":["https:\/\/it-service.network\/"],"url":"https:\/\/it-service.network\/blog\/author\/lena-klaus\/"}]}},"_links":{"self":[{"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/posts\/15178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/comments?post=15178"}],"version-history":[{"count":0,"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/posts\/15178\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/media\/16785"}],"wp:attachment":[{"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/media?parent=15178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/categories?post=15178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/tags?post=15178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}