{"id":2993,"date":"2018-05-25T10:38:34","date_gmt":"2018-05-25T08:38:34","guid":{"rendered":"https:\/\/it-service.network\/blog\/?p=2993"},"modified":"2026-01-30T10:10:50","modified_gmt":"2026-01-30T09:10:50","slug":"eu-datenschutzverordnung","status":"publish","type":"post","link":"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/","title":{"rendered":"EU-Datenschutzverordnung ## Ende der \u00dcbergangsfrist zur Umsetzung der DSGVO"},"content":{"rendered":"<p><strong>Wir schreiben den 25. Mai 2018 \u2013 und damit das Ende der \u00dcbergangsfrist der neuen EU-Datenschutzverordnung. Doch trotz der langen \u00dcbergangsfrist hat kaum ein Unternehmen die Umsetzung der DSGVO fristgerecht geschafft.<\/strong><\/p>\n<p>Wir kl\u00e4ren, welche Gr\u00fcnde es daf\u00fcr gibt und womit Unternehmen in dem Fall rechnen m\u00fcssen.<br \/>\n<!--more--><\/p>\n<div id=\"attachment_2996\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2018\/05\/eu-datenschutzverordnung.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2996\" class=\"size-medium wp-image-2996\" src=\"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2018\/05\/eu-datenschutzverordnung-300x200.jpg\" alt=\"eu-datenschutzverordnung - dsgvo - europ\u00e4ische datenschutzgrundverordnung - eu-datenschutzrichtlinie - datenschutzverordnung\" width=\"300\" height=\"200\" \/><\/a><p id=\"caption-attachment-2996\" class=\"wp-caption-text\">Mit dem 25. Mai 2018 endet die \u00dcbergangsfrist der DSGVO. Doch l\u00e4ngst nicht alle Unternehmen haben deren Umsetzung fristgerecht geschafft.<br \/>(Bild: pixabay.com\/TheDigitalArtist)<\/p><\/div>\n<h3>Ab sofort gilt die EU-Datenschutzverordnung<\/h3>\n<p>Kaum ein Begriff geistert derzeit so oft durch die Medien wie die DSGVO. Zwar gilt die neue <strong>EU-Datenschutzrichtlinie<\/strong> bereits seit knapp zwei Jahren, doch mit dem 25. Mai 2018 endet die \u00dcbergangsfrist zur Umsetzung. Wer die neue <strong>europ\u00e4ische Datenschutzgrundverordnung<\/strong> jetzt noch nicht umgesetzt hat, sieht sich saftigen Strafen gegen\u00fcber: Unternehmen drohen Bu\u00dfgelder von bis zu 20 Millionen Euro oder vier Prozent des weltweiten Umsatzes.<\/p>\n<p>Aber: Kaum ein Unternehmen hat die fristgerechte Umsetzung der DSGVO zum Stichtag 25. Mai 2018 geschafft. Das ergab eine Umfrage des Branchenverbands Bitkom unter 500 Unternehmen zum Stand der Umsetzung der DSGVO. Doch woran liegt es, dass nach wie vor viele Unternehmen bei der Umsetzung der neuen <strong>EU-Datenschutzverordnung<\/strong> hinterherhinken? Auch darauf gibt die Bitkom-Umfrage Antwort.<\/p>\n<h3>EU-Datenschutzverordnung: Unternehmen mit Problemen bei der Umsetzung<\/h3>\n<p>Bereits im April 2018, also rund anderthalb Monate vor dem Ende der DSGVO-\u00dcbergangsfrist, hat Security-Insider-Redakteurin Sarah Gandorfer die <a href=\"https:\/\/www.security-insider.de\/kaum-ein-unternehmen-setzt-dsgvo-fristgerecht-um-a-699732\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ergebnisse der Bitkom-Umfrage zusammengefasst<\/a>. Darin zeigt sich vor allem eins: Viele Unternehmen haben Probleme bei der Umsetzung der neuen <strong>europ\u00e4ischen Datenschutzgrundverordnung<\/strong>.<\/p>\n<p>So arbeiteten im April gerade einmal 13 Prozent der befragten 500 deutschen Unternehmen aktiv an der Umsetzung der <strong>EU-Datenschutzverordnung<\/strong>. Immerhin knapp die H\u00e4lfte der Teilnehmer besch\u00e4ftigte sich zu der Zeit mit den Vorgaben der DSGVO; ein Drittel der Unternehmen gab an, sich bis dato noch gar nicht damit auseinandergesetzt zu haben.<\/p>\n<p>Doch auch Unternehmen, die sich bereits fr\u00fchzeitig an die Einhaltung der neuen <strong>Datenschutzverordnung<\/strong> gemacht haben, haben Probleme, alle Arbeiten fristgerecht abzuschlie\u00dfen. So sagten im April gerade einmal drei Prozent der befragten Unternehmen, dass sie mehr als die H\u00e4lfte der notwendigen Arbeiten abgeschlossen haben.<\/p>\n<h3>EU-Datenschutzverordnung: 3 von 4 Unternehmen verfehlen Frist<\/h3>\n<p>Auch jetzt zum Ende der \u00dcbergangsfrist f\u00fcr die Umsetzung der DSGVO sieht die Lage in den deutschen Unternehmen nicht besser aus. Gerade einmal ein Viertel der Unternehmen ist aus eigener Perspektive mit der Umsetzung der <strong>EU-Datenschutzgrundverordnung<\/strong> rechtzeitig fertig geworden, zeigt eine aktuelle <a href=\"https:\/\/www.bitkom.org\/Presse\/Presseinformation\/3-von-4-Unternehmen-verfehlen-die-Frist-der-Datenschutz-Grundverordnung.html\" target=\"_blank\" rel=\"noopener noreferrer\">Pressemitteilung des Bitkom<\/a>.<\/p>\n<p>Immerhin 32 Prozent der deutschen Unternehmen wird die Anforderungen der <strong>EU-Datenschutzrichtlinie<\/strong> gr\u00f6\u00dftenteils umgesetzt haben, 33 Prozent schaffen die Umsetzung zumindest teilweise. Bedenklich ist jedoch, dass immer noch vier Prozent der Unternehmen ganz am Anfang der Umsetzung der <strong>EU-Datenschutzverordnung<\/strong> stehen. Zwei Prozent der befragten 500 Unternehmen gaben sogar an, bis zum Stichtag 25. Mai 2018 gar nicht mit der Umsetzung der DSGVO anzufangen.<\/p>\n<h3>Warum verfehlen so viele Unternehmen das Ende der \u00dcbergangsfrist?<\/h3>\n<p>Wenn man diese Zahlen sieht, kommt nat\u00fcrlich die Frage auf, warum so viele Unternehmen das Ende der \u00dcbergangsfrist zur Umsetzung der <strong>europ\u00e4ischen Datenschutzgrundverordnung<\/strong> verfehlen. Tats\u00e4chlich gibt es daf\u00fcr verschiedene Gr\u00fcnde, hei\u00dft es in der genannten Bitkom-Pressemitteilung.<\/p>\n<p>So sagt Bitkom-Pr\u00e4sident Achim Berg, dass viele Unternehmen sich in der Vergangenheit zu wenig um das Thema Datenschutz gek\u00fcmmert haben und dadurch nun hohen Nachholbedarf haben. Auch der Aufwand bei der Umsetzung der <strong>EU-Datenschutzverordnung<\/strong> sei ein Problem \u2013 vor allem, da sich dieser nur schwer absch\u00e4tzen l\u00e4sst. Das gaben 66 Prozent der befragten Unternehmen an.<\/p>\n<p>Zudem erwarten 58 Prozent dauerhaft mehr Aufwand f\u00fcr die Einhaltung der <strong>EU-Datenschutzrichtlinie<\/strong>. Insbesondere kleine und mittelst\u00e4ndische Unternehmen sind davon auch langfristig betroffen .<\/p>\n<h3>EU-Datenschutzverordnung: Rechtsunsicherheit ist ein Problem<\/h3>\n<div id=\"attachment_3017\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2018\/05\/eu-datenschutzverordnung-rechtsunsicherheit.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3017\" class=\"size-medium wp-image-3017\" src=\"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2018\/05\/eu-datenschutzverordnung-rechtsunsicherheit-300x199.png\" alt=\"eu-datenschutzverordnung - dsgvo - europ\u00e4ische datenschutzgrundverordnung - eu-datenschutzrichtlinie - datenschutzverordnungeu-datenschutzverordnung - dsgvo - europ\u00e4ische datenschutzgrundverordnung - eu-datenschutzrichtlinie - datenschutzverordnung\" width=\"300\" height=\"199\" \/><\/a><p id=\"caption-attachment-3017\" class=\"wp-caption-text\">Rechtsunsicherheit und der hohe Aufwand bei der Umsetzung sich nur zwei H\u00fcrden f\u00fcr Unternehmen bei der Umsetzung der DSGVO. (Bild: pixabay.com\/geralt)<\/p><\/div>\n<p>Genauso problematisch sehen 56 Prozent der Unternehmen die bestehende Rechtsunsicherheit. Es sind l\u00e4ngst noch nicht alle Fragen zur DSGVO gekl\u00e4rt, und in vielen F\u00e4llen m\u00fcssen erst die ersten Prozesse und Urteile abgewartet werden, um zu sehen, wie die Aufsichtsbeh\u00f6rden entscheiden. Das sorgt bei vielen Unternehmen aber nach wie vor f\u00fcr Unsicherheit.<\/p>\n<p>Wenig \u00fcberraschend w\u00fcnschen sich viele Unternehmen darum eine Verl\u00e4ngerung der Schonfrist (41 Prozent). Au\u00dferdem fordern 49 Prozent der Unternehmen, dass bei Verst\u00f6\u00dfen gegen die <strong>EU-Datenschutzverordnung<\/strong> zun\u00e4chst eine Aufforderung zur Nachbesserung erfolgt, anstatt direkt auf die angek\u00fcndigten harten Sanktionen zur\u00fcckzugreifen.<\/p>\n<h3>Mangelnde Unterst\u00fctzung durch die Beh\u00f6rden wird kritisiert<\/h3>\n<p>Das geht Hand in Hand mit der Kritik an der Unterst\u00fctzung von offizieller Seite. So erkl\u00e4rt Bitkom-Pr\u00e4sident Berg in der oben genannten Pressemitteilung: \u201eBei der Auslegung der Datenschutz-Grundverordnung mangelt es von offizieller Seite bis heute an praktischen Hilfestellungen\u201c. Demnach sollten die Beh\u00f6rden Unternehmen zun\u00e4chst bei der korrekten Umsetzung der <strong>EU-Datenschutzverordnung<\/strong> unterst\u00fctzen, anstatt sie direkt f\u00fcr Verst\u00f6\u00dfe abzustrafen.<\/p>\n<p>\u201eDie zum Teil vagen Formulierungen der Verordnung d\u00fcrften den Unternehmen nicht zum Nachteil ausgelegt werden\u201c, sagt Berg weiter. Allerdings, <a href=\"https:\/\/www.handelsblatt.com\/politik\/deutschland\/dsgvo-unternehmen-koennen-bei-neuen-eu-datenschutzregeln-nicht-auf-nachsicht-hoffen\/22586476.html?ticket=ST-552556-OidIs0EknnKZximoCsJt-ap1\" target=\"_blank\" rel=\"noopener noreferrer\">so schreibt zumindest das Handelsblatt<\/a>, d\u00fcrften die Unternehmen nicht auf allzu viel Nachsicht seitens der Beh\u00f6rden hoffen. Es bleibt also abzuwarten, wie die Beh\u00f6rden in den n\u00e4chsten Wochen und Monaten mit der <strong>EU-Datenschutzverordnung<\/strong> umgehen werden.<\/p>\n<h3>EU-Datenschutzverordnung: Frist abgelaufen \u2013 und jetzt?<\/h3>\n<p>Wir schreiben heute den 25. Mai 2018. Die neue <strong>EU-Datenschutzverordnung<\/strong> gilt damit ab heute offiziell und rechtskr\u00e4ftig. Trotz der zweij\u00e4hrigen \u00dcbergangszeit sind aber l\u00e4ngst nicht alle Unternehmen DSGVO-konform unterwegs, und noch immer gibt es einige Unternehmen, die nicht mal mit der Umsetzung der <strong>europ\u00e4ischen Datenschutzgrundverordnung<\/strong> angefangen haben.<\/p>\n<p>Zu tun gibt es also noch einiges \u2013 nicht nur, was die Umsetzung angeht. Spannend wird auch, wie schnell und in welcher Form die Beh\u00f6rden handeln und wann die ersten Gerichtsurteile zu Verst\u00f6\u00dfen gegen die <strong>EU-Datenschutzverordnung<\/strong> gef\u00e4llt werden. Wenn Sie in Ihrem Unternehmen Hilfe zum Thema <a href=\"https:\/\/it-service.network\/it-sicherheit\/dsgvo-eu-datenschutz-grundverordnung\">DSGVO<\/a> ben\u00f6tigen, empfehlen wir die professionelle Unterst\u00fctzung der <a href=\"https:\/\/it-service.network\/it-dienstleister-finden\">Dienstleister des IT-SERVICE.NETWORK<\/a>. Lassen Sie sich von ihnen zum Thema DSGVO beraten.<\/p>\n<h3>EU-Datenschutzverordnung \u2013 die DSGVO bei uns im \u00dcberblick<\/h3>\n<p>Wir haben uns bereits intensiv mit der europ\u00e4ischen Datenschutzgrundverordnung auseinandergesetzt und \u00fcber wichtige Hinweise zur Umsetzung, interessante Tipps sowie zentrale Gefahren im Blog des <a href=\"https:\/\/it-service.network\/\">IT-SERVICE.NETWORK<\/a> behandelt. Im Folgenden finden Sie noch mal alle Beitr\u00e4ge aus unserem Blog \u00fcbersichtlich aufgelistet:<\/p>\n<ul>\n<li>Was sich in den ersten Monaten getan hat: <a href=\"https:\/\/it-service.network\/blog\/2018\/08\/24\/eu-datenschutzgrundverordnung\/\">drei Monate<\/a> und <a href=\"https:\/\/it-service.network\/blog\/2018\/10\/28\/dsgvo-umsetzung\/\">f\u00fcnf Monate DSGVO<\/a><\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2019\/07\/03\/datenschutz-aenderungen-2019\/\">Datenschutz-\u00c4nderungen im Folgejahr 2019<\/a> \u2013 DSGVO-Anpassung &amp; neue Regel f\u00fcr Datenschutzbeauftragte<\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2018\/10\/02\/dsgvo-abmahnung-verstoss\/\">DSGVO Abmahnung \u2013 Wann und durch wen ist ein Versto\u00df anzeigbar?<\/a><\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2019\/10\/25\/dsgvo-bussgeldbemessung\/\">Bu\u00dfgeldbemessung<\/a> nach DSGVO<\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2019\/05\/29\/dsgvo-meldepflicht\/\">DSGVO-Meldepflicht<\/a><\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2019\/07\/09\/dsgvo-compliance\/\">DSGVO-Konformit\u00e4t (Compliance) testen<\/a><\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2019\/04\/05\/dsgvo-beratung\/\">M\u00f6glichkeiten zur DSGVO-Beratung<\/a><\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2018\/01\/03\/datenschutz-folgenabschaetzung-risikobewertung\/\">Was die Datenschutz-Folgenabsch\u00e4tzun<\/a>g ist und <a href=\"https:\/\/it-service.network\/blog\/2018\/01\/10\/dsgvo-pia-risikoanalyse-wann-ist-dsfa-pflicht\/\">wann Firmen dazu verpflichtet<\/a> sind<\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2017\/09\/28\/auftragsdatenverarbeitung-adv-vertag-aendert-sich\/\">Auftragsdatenverarbeitung \u2013 ADV-Vertr\u00e4ge trotz DSGVO<\/a><\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2018\/02\/23\/verfahrensverzeichnis-nach-dsgvo\/\">Verfahrensverzeichnis<\/a> und \u00a0<a href=\"https:\/\/it-service.network\/blog\/2018\/02\/27\/verarbeitungsverzeichnis-nach-dsgvo\/\">Verarbeitungsverzeichnis nach DSGVO<\/a><\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2018\/04\/03\/tom-datenschutz-toms-dsgvo\/\">TOM Datenschutz<\/a> und<a href=\"https:\/\/it-service.network\/blog\/2018\/04\/13\/toms-dsgvo-datenschutz-datensicherheit\/\"> TOMs DSGVO<\/a> \u2013 Datenschutz und Datensicherheit<\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2019\/09\/12\/privacy-by-design-privacy-by-default\/\">Privacy by Design &amp; Privacy by Default<\/a> \u2013 Technikgestaltung in Zeiten der DSGVO<\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2018\/11\/20\/recht-auf-vergessenwerden\/\">Personenbezogene Daten gem\u00e4\u00df Datenschutzgesetz l\u00f6schen<\/a><\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2019\/03\/28\/einsicht-in-personalakte-auskunftsanspruch\/\">Einsicht in die Personalakte durch Auskunftsanspruch<\/a><\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2019\/07\/26\/datenschutzerklaerung-fuer-bewerber\/\">Datenschutzerkl\u00e4rung f\u00fcr Bewerber<\/a> \u2013 DSGVO-Pflicht f\u00fcr Online-Bewerbungen<\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2019\/02\/28\/public-cloud\/\">Die Public Cloud und die DSGVO<\/a><\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2018\/11\/21\/cloud-act-vs-dsgvo\/\">Cloud-Act vs. DSGVO \u2013 Datenzugriff durch US-Beh\u00f6rden<\/a>; <a href=\"https:\/\/it-service.network\/blog\/2018\/08\/07\/safe-harbor-abkommen\/\">das Safe Habor Abkommen und die Privacy Shield Vereinbarung<\/a> als amerikanische \u00c4quivalente zur DSGVO<\/li>\n<li><a href=\"https:\/\/it-service.network\/blog\/2019\/03\/14\/harter-brexit-dsgvo-probleme\/\">Harter Brexit bringt DSGVO-Probleme \u2013 Die Folgen f\u00fcr Datentransfers mit Gro\u00dfbritannien<\/a><\/li>\n<\/ul>\n<p>Sie ben\u00f6tigen Unterst\u00fctzung bei der Umsetzung der neuen EU-Datenschutzrichtlinie? Dann nehmen Sie Kontakt zu den <a href=\"https:\/\/it-service.network\/it-dienstleister-finden\">Dienstleistern des IT-SERVICE.NETWORK<\/a> auf und lassen Sie sich dazu beraten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir schreiben den 25. Mai 2018 \u2013 und damit das Ende der \u00dcbergangsfrist der neuen EU-Datenschutzverordnung. Doch trotz der langen \u00dcbergangsfrist hat kaum ein Unternehmen die Umsetzung der DSGVO fristgerecht geschafft. Wir kl\u00e4ren, welche Gr\u00fcnde es daf\u00fcr gibt und womit Unternehmen in dem Fall rechnen m\u00fcssen.<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[156,899],"class_list":["post-2993","post","type-post","status-publish","format-standard","hentry","category-it-sicherheit","tag-dsgvo","tag-it-recht-und-digitalpolitik"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EU-Datenschutzverordnung \u2013 \u00dcbergangsfrist ist zu Ende<\/title>\n<meta name=\"description\" content=\"Am 25. Mai 2018 endete die \u00dcbergangsfrist der EU-Datenschutzverordnung, doch kaum ein Betrieb setzte die DSGVO fristgerecht um. Warum?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EU-Datenschutzverordnung \u2013 \u00dcbergangsfrist ist zu Ende\" \/>\n<meta property=\"og:description\" content=\"Am 25. Mai 2018 endete die \u00dcbergangsfrist der EU-Datenschutzverordnung, doch kaum ein Betrieb setzte die DSGVO fristgerecht um. Warum?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/\" \/>\n<meta property=\"og:site_name\" content=\"IT-SERVICE.NETWORK Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/itservicenetwork\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-25T08:38:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T09:10:50+00:00\" \/>\n<meta name=\"author\" content=\"IT-SERVICE.NETWORK-Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ITSERVICNETWORK\" \/>\n<meta name=\"twitter:site\" content=\"@ITSERVICNETWORK\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"IT-SERVICE.NETWORK-Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/\",\"url\":\"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/\",\"name\":\"EU-Datenschutzverordnung \u2013 \u00dcbergangsfrist ist zu Ende\",\"isPartOf\":{\"@id\":\"https:\/\/it-service.network\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2018\/05\/eu-datenschutzverordnung-300x200.jpg\",\"datePublished\":\"2018-05-25T08:38:34+00:00\",\"dateModified\":\"2026-01-30T09:10:50+00:00\",\"author\":{\"@id\":\"https:\/\/it-service.network\/blog\/#\/schema\/person\/275538ad651c88acf1bc71759036143a\"},\"description\":\"Am 25. Mai 2018 endete die \u00dcbergangsfrist der EU-Datenschutzverordnung, doch kaum ein Betrieb setzte die DSGVO fristgerecht um. Warum?\",\"breadcrumb\":{\"@id\":\"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/#primaryimage\",\"url\":\"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2018\/05\/eu-datenschutzverordnung-300x200.jpg\",\"contentUrl\":\"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2018\/05\/eu-datenschutzverordnung-300x200.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/it-service.network\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EU-Datenschutzverordnung ## Ende der \u00dcbergangsfrist zur Umsetzung der DSGVO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/it-service.network\/blog\/#website\",\"url\":\"https:\/\/it-service.network\/blog\/\",\"name\":\"IT-SERVICE.NETWORK Blog\",\"description\":\"Der IT-SERVICE.NETWORK Blog mit spannenden IT-News: \u2713 IT-Themen \u2713 IT-Trends \u2713 Business-Themen \u2713 IT-Dienstleistungen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/it-service.network\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/it-service.network\/blog\/#\/schema\/person\/275538ad651c88acf1bc71759036143a\",\"name\":\"IT-SERVICE.NETWORK-Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/it-service.network\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/86ef1115edcb7b1651f082979941c8f018129accb2eff4a77ad593cdddeee715?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/86ef1115edcb7b1651f082979941c8f018129accb2eff4a77ad593cdddeee715?s=96&d=mm&r=g\",\"caption\":\"IT-SERVICE.NETWORK-Redaktion\"},\"url\":\"https:\/\/it-service.network\/blog\/author\/it-service-network-redaktion\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EU-Datenschutzverordnung \u2013 \u00dcbergangsfrist ist zu Ende","description":"Am 25. Mai 2018 endete die \u00dcbergangsfrist der EU-Datenschutzverordnung, doch kaum ein Betrieb setzte die DSGVO fristgerecht um. Warum?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/","og_locale":"de_DE","og_type":"article","og_title":"EU-Datenschutzverordnung \u2013 \u00dcbergangsfrist ist zu Ende","og_description":"Am 25. Mai 2018 endete die \u00dcbergangsfrist der EU-Datenschutzverordnung, doch kaum ein Betrieb setzte die DSGVO fristgerecht um. Warum?","og_url":"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/","og_site_name":"IT-SERVICE.NETWORK Blog","article_publisher":"https:\/\/www.facebook.com\/itservicenetwork\/","article_published_time":"2018-05-25T08:38:34+00:00","article_modified_time":"2026-01-30T09:10:50+00:00","author":"IT-SERVICE.NETWORK-Redaktion","twitter_card":"summary_large_image","twitter_creator":"@ITSERVICNETWORK","twitter_site":"@ITSERVICNETWORK","twitter_misc":{"Verfasst von":"IT-SERVICE.NETWORK-Redaktion","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/","url":"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/","name":"EU-Datenschutzverordnung \u2013 \u00dcbergangsfrist ist zu Ende","isPartOf":{"@id":"https:\/\/it-service.network\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/#primaryimage"},"image":{"@id":"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/#primaryimage"},"thumbnailUrl":"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2018\/05\/eu-datenschutzverordnung-300x200.jpg","datePublished":"2018-05-25T08:38:34+00:00","dateModified":"2026-01-30T09:10:50+00:00","author":{"@id":"https:\/\/it-service.network\/blog\/#\/schema\/person\/275538ad651c88acf1bc71759036143a"},"description":"Am 25. Mai 2018 endete die \u00dcbergangsfrist der EU-Datenschutzverordnung, doch kaum ein Betrieb setzte die DSGVO fristgerecht um. Warum?","breadcrumb":{"@id":"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/#primaryimage","url":"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2018\/05\/eu-datenschutzverordnung-300x200.jpg","contentUrl":"https:\/\/it-service.network\/blog\/wp-content\/uploads\/2018\/05\/eu-datenschutzverordnung-300x200.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/it-service.network\/blog\/2018\/05\/25\/eu-datenschutzverordnung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/it-service.network\/blog\/"},{"@type":"ListItem","position":2,"name":"EU-Datenschutzverordnung ## Ende der \u00dcbergangsfrist zur Umsetzung der DSGVO"}]},{"@type":"WebSite","@id":"https:\/\/it-service.network\/blog\/#website","url":"https:\/\/it-service.network\/blog\/","name":"IT-SERVICE.NETWORK Blog","description":"Der IT-SERVICE.NETWORK Blog mit spannenden IT-News: \u2713 IT-Themen \u2713 IT-Trends \u2713 Business-Themen \u2713 IT-Dienstleistungen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/it-service.network\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/it-service.network\/blog\/#\/schema\/person\/275538ad651c88acf1bc71759036143a","name":"IT-SERVICE.NETWORK-Redaktion","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/it-service.network\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/86ef1115edcb7b1651f082979941c8f018129accb2eff4a77ad593cdddeee715?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/86ef1115edcb7b1651f082979941c8f018129accb2eff4a77ad593cdddeee715?s=96&d=mm&r=g","caption":"IT-SERVICE.NETWORK-Redaktion"},"url":"https:\/\/it-service.network\/blog\/author\/it-service-network-redaktion\/"}]}},"_links":{"self":[{"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/posts\/2993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/comments?post=2993"}],"version-history":[{"count":3,"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/posts\/2993\/revisions"}],"predecessor-version":[{"id":29968,"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/posts\/2993\/revisions\/29968"}],"wp:attachment":[{"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/media?parent=2993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/categories?post=2993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/it-service.network\/blog\/wp-json\/wp\/v2\/tags?post=2993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}